{"id":394,"count":1,"description":"","link":"https:\/\/bukabanten.co.id\/news\/tag\/dprd-kota-serang\/","name":"DPRD Kota Serang","slug":"dprd-kota-serang","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/bukabanten.co.id\/news\/tag\/dprd-kota-serang\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bukabanten.co.id\\\/news\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/394\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bukabanten.co.id\\\/news#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bukabanten.co.id\\\/news\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bukabanten.co.id\\\/news\\\/tag\\\/dprd-kota-serang\\\/#listItem\",\"name\":\"DPRD Kota Serang\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bukabanten.co.id\\\/news\\\/tag\\\/dprd-kota-serang\\\/#listItem\",\"position\":2,\"name\":\"DPRD Kota Serang\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bukabanten.co.id\\\/news#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/bukabanten.co.id\\\/news\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/394\\\/#collectionpage\",\"url\":\"https:\\\/\\\/bukabanten.co.id\\\/news\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/394\\\/\",\"name\":\"DPRD Kota Serang - Bukabanten\",\"inLanguage\":\"id-ID\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bukabanten.co.id\\\/news\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bukabanten.co.id\\\/news\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/394\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bukabanten.co.id\\\/news\\\/#organization\",\"name\":\"Bukabanten\",\"description\":\"Jendala Informasi Banten\",\"url\":\"https:\\\/\\\/bukabanten.co.id\\\/news\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/share\\\/18DDULPXkq\\\/\",\"https:\\\/\\\/www.instagram.com\\\/bukabanten?utm_source=qr&igsh=dmdlZjB2dXdkNjJw\",\"https:\\\/\\\/www.tiktok.com\\\/@bukabanten.co.id?_r=1&_t=ZS-96pvSta3yM9\",\"https:\\\/\\\/youtube.com\\\/@bukabanten?si=m7ch4f3r32UL4zdo\",\"https:\\\/\\\/www.threads.com\\\/@bukabanten\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bukabanten.co.id\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/bukabanten.co.id\\\/news\\\/\",\"name\":\"Bukabanten\",\"description\":\"Jendala Informasi Banten\",\"inLanguage\":\"id-ID\",\"publisher\":{\"@id\":\"https:\\\/\\\/bukabanten.co.id\\\/news\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"DPRD Kota Serang - Bukabanten","description":"","canonical_url":"https:\/\/bukabanten.co.id\/news\/tag\/dprd-kota-serang\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/bukabanten.co.id\/news\/wp-json\/wp\/v2\/tags\/394\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/bukabanten.co.id\/news#listItem","position":1,"name":"Home","item":"https:\/\/bukabanten.co.id\/news","nextItem":{"@type":"ListItem","@id":"https:\/\/bukabanten.co.id\/news\/tag\/dprd-kota-serang\/#listItem","name":"DPRD Kota Serang"}},{"@type":"ListItem","@id":"https:\/\/bukabanten.co.id\/news\/tag\/dprd-kota-serang\/#listItem","position":2,"name":"DPRD Kota Serang","previousItem":{"@type":"ListItem","@id":"https:\/\/bukabanten.co.id\/news#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/bukabanten.co.id\/news\/wp-json\/wp\/v2\/tags\/394\/#collectionpage","url":"https:\/\/bukabanten.co.id\/news\/wp-json\/wp\/v2\/tags\/394\/","name":"DPRD Kota Serang - Bukabanten","inLanguage":"id-ID","isPartOf":{"@id":"https:\/\/bukabanten.co.id\/news\/#website"},"breadcrumb":{"@id":"https:\/\/bukabanten.co.id\/news\/wp-json\/wp\/v2\/tags\/394\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/bukabanten.co.id\/news\/#organization","name":"Bukabanten","description":"Jendala Informasi Banten","url":"https:\/\/bukabanten.co.id\/news\/","sameAs":["https:\/\/www.facebook.com\/share\/18DDULPXkq\/","https:\/\/www.instagram.com\/bukabanten?utm_source=qr&igsh=dmdlZjB2dXdkNjJw","https:\/\/www.tiktok.com\/@bukabanten.co.id?_r=1&_t=ZS-96pvSta3yM9","https:\/\/youtube.com\/@bukabanten?si=m7ch4f3r32UL4zdo","https:\/\/www.threads.com\/@bukabanten"]},{"@type":"WebSite","@id":"https:\/\/bukabanten.co.id\/news\/#website","url":"https:\/\/bukabanten.co.id\/news\/","name":"Bukabanten","description":"Jendala Informasi Banten","inLanguage":"id-ID","publisher":{"@id":"https:\/\/bukabanten.co.id\/news\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bukabanten.co.id\/news\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDPRD Kota Serang\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/bukabanten.co.id\/news"},{"label":"DPRD Kota Serang","link":"https:\/\/bukabanten.co.id\/news\/tag\/dprd-kota-serang\/"}],"_links":{"self":[{"href":"https:\/\/bukabanten.co.id\/news\/wp-json\/wp\/v2\/tags\/394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bukabanten.co.id\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bukabanten.co.id\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bukabanten.co.id\/news\/wp-json\/wp\/v2\/posts?tags=394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}